{"id":1995,"date":"2021-01-06T17:01:24","date_gmt":"2021-01-06T16:01:24","guid":{"rendered":"https:\/\/stagpartynight.com\/es\/?post_type=product&#038;p=1995"},"modified":"2022-12-22T12:28:15","modified_gmt":"2022-12-22T11:28:15","slug":"tour-en-bicicleta-por-varsovia","status":"publish","type":"product","link":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/","title":{"rendered":"Tour en bicicleta por Varsovia"},"content":{"rendered":"<p>Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aproximadamente. Visita de alta calidad, con gu\u00eda local privado. Posibilidad en varios idiomas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aproximadamente. Visita de alta calidad, con gu\u00eda local privado. Posibilidad en varios idiomas<\/p>\n","protected":false},"featured_media":1997,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[291],"product_tag":[331,329,330,328,327],"class_list":{"0":"post-1995","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-varsovia","7":"product_tag-bici-varsovia","8":"product_tag-bicicletas-varsovia","9":"product_tag-bicis","10":"product_tag-ruta-en-bicicleta-en-varsovia","11":"product_tag-tour-en-bici-en-varsovia","13":"first","14":"instock","15":"virtual","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tour en bicicleta por Varsovia - Tour en bicicleta en Varsovia<\/title>\n<meta name=\"description\" content=\"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour en bicicleta por Varsovia\" \/>\n<meta property=\"og:description\" content=\"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/\" \/>\n<meta property=\"og:site_name\" content=\"Despedida de Soltero\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-22T11:28:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2021\/01\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"712\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/\",\"name\":\"Tour en bicicleta por Varsovia - Tour en bicicleta en Varsovia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg\",\"datePublished\":\"2021-01-06T16:01:24+00:00\",\"dateModified\":\"2022-12-22T11:28:15+00:00\",\"description\":\"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg\",\"contentUrl\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg\",\"width\":712,\"height\":339},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/product\\\/tour-en-bicicleta-por-varsovia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tour en bicicleta por Varsovia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/\",\"name\":\"Stag Party Night\",\"description\":\"Your Stag Party Customized\",\"publisher\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#organization\",\"name\":\"Stag Party Night\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/stagpartynight-e1578565505687.png\",\"contentUrl\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/stagpartynight-e1578565505687.png\",\"width\":400,\"height\":400,\"caption\":\"Stag Party Night\"},\"image\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour en bicicleta por Varsovia - Tour en bicicleta en Varsovia","description":"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/","og_locale":"es_ES","og_type":"article","og_title":"Tour en bicicleta por Varsovia","og_description":"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.","og_url":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/","og_site_name":"Despedida de Soltero","article_modified_time":"2022-12-22T11:28:15+00:00","og_image":[{"width":712,"height":339,"url":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2021\/01\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/","url":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/","name":"Tour en bicicleta por Varsovia - Tour en bicicleta en Varsovia","isPartOf":{"@id":"https:\/\/stagpartynight.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/#primaryimage"},"image":{"@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/#primaryimage"},"thumbnailUrl":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2021\/01\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg","datePublished":"2021-01-06T16:01:24+00:00","dateModified":"2022-12-22T11:28:15+00:00","description":"Tour en bicicleta por Varsovia - Conoce la historia de Varsovia en un tour en bicicleta de 2,5 horas aprox. Visita de alta calidad, con gu\u00eda local privado.","breadcrumb":{"@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/#primaryimage","url":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2021\/01\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg","contentUrl":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2021\/01\/WhatsApp-Image-2021-01-06-at-16.10.36.jpeg","width":712,"height":339},{"@type":"BreadcrumbList","@id":"https:\/\/stagpartynight.com\/es\/product\/tour-en-bicicleta-por-varsovia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stagpartynight.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/stagpartynight.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Tour en bicicleta por Varsovia"}]},{"@type":"WebSite","@id":"https:\/\/stagpartynight.com\/es\/#website","url":"https:\/\/stagpartynight.com\/es\/","name":"Stag Party Night","description":"Your Stag Party Customized","publisher":{"@id":"https:\/\/stagpartynight.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stagpartynight.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/stagpartynight.com\/es\/#organization","name":"Stag Party Night","url":"https:\/\/stagpartynight.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stagpartynight.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2019\/12\/stagpartynight-e1578565505687.png","contentUrl":"https:\/\/stagpartynight.com\/es\/wp-content\/uploads\/sites\/2\/2019\/12\/stagpartynight-e1578565505687.png","width":400,"height":400,"caption":"Stag Party Night"},"image":{"@id":"https:\/\/stagpartynight.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/product\/1995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/comments?post=1995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/media\/1997"}],"wp:attachment":[{"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/media?parent=1995"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/product_brand?post=1995"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/product_cat?post=1995"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stagpartynight.com\/es\/wp-json\/wp\/v2\/product_tag?post=1995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}