{"id":3452,"date":"2022-01-26T19:05:46","date_gmt":"2022-01-26T18:05:46","guid":{"rendered":"https:\/\/stagpartynight.com\/it\/?post_type=product&#038;p=3452"},"modified":"2022-01-26T19:06:51","modified_gmt":"2022-01-26T18:06:51","slug":"bubble-football-madrid","status":"publish","type":"product","link":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/","title":{"rendered":"Bubble Football Madrid"},"content":{"rendered":"<p>Un diverso tipo di competizione calcistica. Tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L&#8217;obiettivo \u00e8 quello di segnare pi\u00f9 gol dell&#8217;avversario ma, non ci sono regole! Attrezzatura, arbitri e spogliatoi con docce private sono inclusi. Durata 1 ora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un diverso tipo di competizione calcistica. Tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L&#8217;obiettivo \u00e8 quello di segnare pi\u00f9 gol dell&#8217;avversario ma, non ci sono regole! Attrezzatura, arbitri e spogliatoi con docce private sono inclusi. Durata 1 ora.<\/p>\n","protected":false},"featured_media":184,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[180],"product_tag":[55,1182],"class_list":{"0":"post-3452","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-madrid","7":"product_tag-bubble-football","8":"product_tag-bubble-football-madrid","10":"first","11":"instock","12":"virtual","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bubble Football Madrid - Calcio a Madrid - Attivit\u00e0 di Madrid<\/title>\n<meta name=\"description\" content=\"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L&#039;obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bubble Football Madrid\" \/>\n<meta property=\"og:description\" content=\"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L&#039;obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Addii - Scopri le idee pi\u00f9 originali per il tuo prossimo addio\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-26T18:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2020\/01\/bubble-football.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/\",\"name\":\"Bubble Football Madrid - Calcio a Madrid - Attivit\u00e0 di Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/01\\\/bubble-football.jpg\",\"datePublished\":\"2022-01-26T18:05:46+00:00\",\"dateModified\":\"2022-01-26T18:06:51+00:00\",\"description\":\"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L'obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/01\\\/bubble-football.jpg\",\"contentUrl\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2020\\\/01\\\/bubble-football.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/product\\\/bubble-football-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bubble Football Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/\",\"name\":\"Stag Party Night\",\"description\":\"Your Stag Party Customized\",\"publisher\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#organization\",\"name\":\"Stag Party Night\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/12\\\/stagpartynight-e1578565505687.png\",\"contentUrl\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2019\\\/12\\\/stagpartynight-e1578565505687.png\",\"width\":400,\"height\":400,\"caption\":\"Stag Party Night\"},\"image\":{\"@id\":\"https:\\\/\\\/stagpartynight.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bubble Football Madrid - Calcio a Madrid - Attivit\u00e0 di Madrid","description":"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L'obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Bubble Football Madrid","og_description":"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L'obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!","og_url":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/","og_site_name":"Addii - Scopri le idee pi\u00f9 originali per il tuo prossimo addio","article_modified_time":"2022-01-26T18:06:51+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2020\/01\/bubble-football.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/","url":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/","name":"Bubble Football Madrid - Calcio a Madrid - Attivit\u00e0 di Madrid","isPartOf":{"@id":"https:\/\/stagpartynight.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/#primaryimage"},"image":{"@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2020\/01\/bubble-football.jpg","datePublished":"2022-01-26T18:05:46+00:00","dateModified":"2022-01-26T18:06:51+00:00","description":"Bubble Football Madrid - Un diverso tipo di competizione calcistica in cui tu e i tuoi amici sarete divisi in due squadre di 5 e 5. L'obiettivo \u00e8 quello di segnare pi\u00f9 gol del tuo avversario ma, non ci sono regole!","breadcrumb":{"@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/#primaryimage","url":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2020\/01\/bubble-football.jpg","contentUrl":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2020\/01\/bubble-football.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/stagpartynight.com\/it\/product\/bubble-football-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stagpartynight.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/stagpartynight.com\/it\/tienda\/"},{"@type":"ListItem","position":3,"name":"Bubble Football Madrid"}]},{"@type":"WebSite","@id":"https:\/\/stagpartynight.com\/it\/#website","url":"https:\/\/stagpartynight.com\/it\/","name":"Stag Party Night","description":"Your Stag Party Customized","publisher":{"@id":"https:\/\/stagpartynight.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stagpartynight.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/stagpartynight.com\/it\/#organization","name":"Stag Party Night","url":"https:\/\/stagpartynight.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stagpartynight.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2019\/12\/stagpartynight-e1578565505687.png","contentUrl":"https:\/\/stagpartynight.com\/it\/wp-content\/uploads\/sites\/10\/2019\/12\/stagpartynight-e1578565505687.png","width":400,"height":400,"caption":"Stag Party Night"},"image":{"@id":"https:\/\/stagpartynight.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/product\/3452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/comments?post=3452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/media\/184"}],"wp:attachment":[{"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/media?parent=3452"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/product_brand?post=3452"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/product_cat?post=3452"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stagpartynight.com\/it\/wp-json\/wp\/v2\/product_tag?post=3452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}